{"id":88,"count":1,"description":"","link":"https:\/\/lessgovisthebestgov.com\/blog\/tag\/october-jobs-report\/","name":"October Jobs Report","slug":"october-jobs-report","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lessgovisthebestgov.com\/blog\/wp-json\/wp\/v2\/tags\/88"}],"collection":[{"href":"https:\/\/lessgovisthebestgov.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lessgovisthebestgov.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lessgovisthebestgov.com\/blog\/wp-json\/wp\/v2\/posts?tags=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}